{"id":9854,"date":"2026-04-24T11:57:38","date_gmt":"2026-04-24T10:57:38","guid":{"rendered":"https:\/\/mstchemicals.com\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/"},"modified":"2026-04-24T11:57:38","modified_gmt":"2026-04-24T10:57:38","slug":"articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine","status":"publish","type":"post","link":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/","title":{"rendered":"Articolo del Gruppo CIE e MST Chemicals su Can Tech International Magazine"},"content":{"rendered":"<p>CIE &amp; MST Chemicals Group is pleased to inform you that <strong>CanTech International magazine<\/strong> (on July issue), specialized in metal packaging sector, has dedicated the following article to us: \u201cChemical collaboration\u201d.<\/p>\n<p>Scopri di pi\u00f9 sul nostro gruppo, i nostri prodotti e le nostre tecnologie innovative!<\/p>\n<p><strong><a href=\"\/wp-content\/uploads\/page-24-26-from-ct-july-22.pdf\" target=\"_blank\" rel=\"noopener\">Leggi l&#8217;articolo<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rivista CanTech International (nel numero di luglio) ha dedicato l&#8217;articolo &#8220;Chemical collaboration&#8221; al Gruppo CIE &#038; MST Chemicals.<\/p>\n","protected":false},"author":1,"featured_media":9478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIE &amp; MST Group su Can Tech International Magazine | MST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIE &amp; MST Group su Can Tech International Magazine | MST\" \/>\n<meta property=\"og:description\" content=\"La rivista CanTech International (nel numero di luglio) ha dedicato l&#039;articolo &quot;Chemical collaboration&quot; al Gruppo CIE &amp; MST Chemicals.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/\" \/>\n<meta property=\"og:site_name\" content=\"MST Chemicals\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-24T10:57:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mstchemicals.com\/wp-content\/uploads\/Immagine-2022-06-30-095533.png\" \/>\n\t<meta property=\"og:image:width\" content=\"588\" \/>\n\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/#\\\/schema\\\/person\\\/ef31c19c9a06908537a774674408397c\"},\"headline\":\"Articolo del Gruppo CIE e MST Chemicals su Can Tech International Magazine\",\"datePublished\":\"2026-04-24T10:57:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/\"},\"wordCount\":60,\"image\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mstchemicals.com\\\/wp-content\\\/uploads\\\/Immagine-2022-06-30-095533.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/\",\"url\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/\",\"name\":\"CIE & MST Group su Can Tech International Magazine | MST\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mstchemicals.com\\\/wp-content\\\/uploads\\\/Immagine-2022-06-30-095533.png\",\"datePublished\":\"2026-04-24T10:57:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/#\\\/schema\\\/person\\\/ef31c19c9a06908537a774674408397c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mstchemicals.com\\\/wp-content\\\/uploads\\\/Immagine-2022-06-30-095533.png\",\"contentUrl\":\"https:\\\/\\\/mstchemicals.com\\\/wp-content\\\/uploads\\\/Immagine-2022-06-30-095533.png\",\"width\":588,\"height\":366,\"caption\":\"mst chemicals new headquarter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articolo del Gruppo CIE e MST Chemicals su Can Tech International Magazine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/\",\"name\":\"MST Chemicals\",\"description\":\"Chemicals and Technologies for waste Water treatment &amp; Zero Liquid Discharge\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mstchemicals.com\\\/it\\\/#\\\/schema\\\/person\\\/ef31c19c9a06908537a774674408397c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76a459e169430884d670891624efea7e01736a4760772dfec4d81898cf2439c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76a459e169430884d670891624efea7e01736a4760772dfec4d81898cf2439c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76a459e169430884d670891624efea7e01736a4760772dfec4d81898cf2439c6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/mstchemicals.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIE & MST Group su Can Tech International Magazine | MST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/","og_locale":"it_IT","og_type":"article","og_title":"CIE & MST Group su Can Tech International Magazine | MST","og_description":"La rivista CanTech International (nel numero di luglio) ha dedicato l'articolo \"Chemical collaboration\" al Gruppo CIE & MST Chemicals.","og_url":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/","og_site_name":"MST Chemicals","article_published_time":"2026-04-24T10:57:38+00:00","og_image":[{"width":588,"height":366,"url":"https:\/\/mstchemicals.com\/wp-content\/uploads\/Immagine-2022-06-30-095533.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/#article","isPartOf":{"@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/"},"author":{"name":"admin","@id":"https:\/\/mstchemicals.com\/it\/#\/schema\/person\/ef31c19c9a06908537a774674408397c"},"headline":"Articolo del Gruppo CIE e MST Chemicals su Can Tech International Magazine","datePublished":"2026-04-24T10:57:38+00:00","mainEntityOfPage":{"@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/"},"wordCount":60,"image":{"@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/#primaryimage"},"thumbnailUrl":"https:\/\/mstchemicals.com\/wp-content\/uploads\/Immagine-2022-06-30-095533.png","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/","url":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/","name":"CIE & MST Group su Can Tech International Magazine | MST","isPartOf":{"@id":"https:\/\/mstchemicals.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/#primaryimage"},"image":{"@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/#primaryimage"},"thumbnailUrl":"https:\/\/mstchemicals.com\/wp-content\/uploads\/Immagine-2022-06-30-095533.png","datePublished":"2026-04-24T10:57:38+00:00","author":{"@id":"https:\/\/mstchemicals.com\/it\/#\/schema\/person\/ef31c19c9a06908537a774674408397c"},"breadcrumb":{"@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/#primaryimage","url":"https:\/\/mstchemicals.com\/wp-content\/uploads\/Immagine-2022-06-30-095533.png","contentUrl":"https:\/\/mstchemicals.com\/wp-content\/uploads\/Immagine-2022-06-30-095533.png","width":588,"height":366,"caption":"mst chemicals new headquarter"},{"@type":"BreadcrumbList","@id":"https:\/\/mstchemicals.com\/it\/articolo-gruppo-cie-mst-chemicals-can-tech-international-magazine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mstchemicals.com\/it\/"},{"@type":"ListItem","position":2,"name":"Articolo del Gruppo CIE e MST Chemicals su Can Tech International Magazine"}]},{"@type":"WebSite","@id":"https:\/\/mstchemicals.com\/it\/#website","url":"https:\/\/mstchemicals.com\/it\/","name":"MST Chemicals","description":"Chemicals and Technologies for waste Water treatment &amp; Zero Liquid Discharge","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mstchemicals.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/mstchemicals.com\/it\/#\/schema\/person\/ef31c19c9a06908537a774674408397c","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/76a459e169430884d670891624efea7e01736a4760772dfec4d81898cf2439c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/76a459e169430884d670891624efea7e01736a4760772dfec4d81898cf2439c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76a459e169430884d670891624efea7e01736a4760772dfec4d81898cf2439c6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/mstchemicals.com"]}]}},"_links":{"self":[{"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/posts\/9854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/comments?post=9854"}],"version-history":[{"count":0,"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/posts\/9854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/media\/9478"}],"wp:attachment":[{"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/media?parent=9854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/categories?post=9854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mstchemicals.com\/it\/wp-json\/wp\/v2\/tags?post=9854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}